{"id":1097,"date":"2023-11-06T13:56:22","date_gmt":"2023-11-06T13:56:22","guid":{"rendered":"https:\/\/wondertools.com.tr\/?post_type=product&#038;p=1097"},"modified":"2023-11-24T13:08:09","modified_gmt":"2023-11-24T13:08:09","slug":"ithal-sds-plus-genis-keski-14x250x40-mm","status":"publish","type":"product","link":"https:\/\/wondertools.com.tr\/ru\/product\/ithal-sds-plus-genis-keski-14x250x40-mm\/","title":{"rendered":"\u0427\u0443\u0434\u043e-\u043f\u043b\u043e\u0441\u043a\u0430\u044f \u043a\u0430\u043d\u0430\u0432\u043a\u0430 Sds Max"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1363,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[105,106],"product_tag":[],"class_list":["post-1097","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-aksesuarlar","product_cat-murc-ve-keski"],"acf":[],"_links":{"self":[{"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/product\/1097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/comments?post=1097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/media\/1363"}],"wp:attachment":[{"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/media?parent=1097"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/product_cat?post=1097"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wondertools.com.tr\/ru\/wp-json\/wp\/v2\/product_tag?post=1097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}